{"id":13543,"date":"2015-04-16T19:01:17","date_gmt":"2015-04-16T19:01:17","guid":{"rendered":"http:\/\/www.sommelierwine.com.br\/?p=13543"},"modified":"2025-09-17T10:26:48","modified_gmt":"2025-09-17T13:26:48","slug":"viagem-a-bodega-goulart","status":"publish","type":"post","link":"https:\/\/www.wine.com.br\/winepedia\/viagem-a-bodega-goulart\/","title":{"rendered":"Viagem dos Wineanos \u00e0 Bodega Goulart"},"content":{"rendered":"<p>Na nossa Conven\u00e7\u00e3o Wine &#8211; um encontro anual de todos os Wineanos &#8211; de 2014, algumas passagens foram sorteadas, por produtores de vinhos de v\u00e1rios lugares do mundo, de vin\u00edcolas que s\u00e3o nossas parceiras.<\/p>\n<p>No dia 08 de abril, aconteceu a primeira viagem, na qual 10 Wineanos partiram para uma experi\u00eancia incr\u00edvel: uma colheita na exclusiva <strong>Bodega Goulart<\/strong>, em Luj\u00e1n de Cuyo, Mendoza, na Argentina.<\/p>\n<p>A brasileira Erika Goulart, propriet\u00e1ria da vin\u00edcola, preparou um roteiro muito especial. O foco era a colheita das uvas que d\u00e3o vida ao seu vinho \u00edcone, o <a href=\"https:\/\/www.wine.com.br\/vinhos\/goulart-grand-vin-malbec-single-vineyard-2008\/prod8398.html?utm_source=winepedia&amp;utm_medium=socialorganic&amp;utm_campaign=16.04.2015-goulart-gran-vin-malbec-vineyard\" target=\"_blank\" rel=\"noopener noreferrer\">Goulart Grand Vin Malbec Single Vineyard<\/a>, e todo o processo de elabora\u00e7\u00e3o do exemplar.<\/p>\n<p>S\u00f3 isso j\u00e1 seria fant\u00e1stico, por\u00e9m, outras surpresas e aventuras esperavam por nossos Wineanos.<\/p>\n<p>A recep\u00e7\u00e3o foi com um delicioso churrasco no meio dos vinhedos. Nesse primeiro momento, Erika, seu agr\u00f4nomo Marcelo Canatella e Jos\u00e9 Hidalgo, um de seus en\u00f3logos, explicaram todo o terroir da regi\u00e3o, tiraram d\u00favidas e proporcionaram uma caminhada entre as vinhas,\u00a0com uma ta\u00e7a de vinho.<\/p>\n<p><a href=\"https:\/\/www.winepedia.com.br\/wp-content\/uploads\/2015\/04\/IMG_03421.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13617 \" src=\"https:\/\/www.wine.com.br\/winepedia\/wp-content\/uploads\/2015\/04\/IMG_03421.jpg\" alt=\"IMG_0342\" width=\"602\" height=\"401\" srcset=\"https:\/\/www.wine.com.br\/winepedia\/wp-content\/uploads\/2015\/04\/IMG_03421.jpg 2048w, https:\/\/www.wine.com.br\/winepedia\/wp-content\/uploads\/2015\/04\/IMG_03421-300x200.jpg 300w, https:\/\/www.wine.com.br\/winepedia\/wp-content\/uploads\/2015\/04\/IMG_03421-768x512.jpg 768w, https:\/\/www.wine.com.br\/winepedia\/wp-content\/uploads\/2015\/04\/IMG_03421-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 602px) 100vw, 602px\" \/><\/a><\/p>\n<p>No dia seguinte, todos participaram da colheita junto aos\u00a0trabalhadores da vin\u00edcola. Entre muitas risadas e fotos, os Wineanos sentiram na pele todo o trabalho e dificuldade de uma colheita.<\/p>\n<p>Sob sol e calor, fileiras e mais fileiras de uvas precisavam ser colhidas e, al\u00e9m de colh\u00ea-las, era preciso\u00a0carregar as caixas &#8211; que pesam cerca de 20 kg &#8211; at\u00e9 o ponto de organiza\u00e7\u00e3o.<\/p>\n<p><a href=\"https:\/\/www.winepedia.com.br\/wp-content\/uploads\/2015\/04\/^460CE01E91CA6BB77DE9C94DF6958F122A81D73268C195608E^pimgpsh_fullsize_distr1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13619 \" src=\"https:\/\/www.wine.com.br\/winepedia\/wp-content\/uploads\/2015\/04\/^460CE01E91CA6BB77DE9C94DF6958F122A81D73268C195608E^pimgpsh_fullsize_distr1.jpg\" alt=\"^460CE01E91CA6BB77DE9C94DF6958F122A81D73268C195608E^pimgpsh_fullsize_distr\" width=\"600\" height=\"600\" srcset=\"https:\/\/www.wine.com.br\/winepedia\/wp-content\/uploads\/2015\/04\/^460CE01E91CA6BB77DE9C94DF6958F122A81D73268C195608E^pimgpsh_fullsize_distr1.jpg 1024w, https:\/\/www.wine.com.br\/winepedia\/wp-content\/uploads\/2015\/04\/^460CE01E91CA6BB77DE9C94DF6958F122A81D73268C195608E^pimgpsh_fullsize_distr1-150x150.jpg 150w, https:\/\/www.wine.com.br\/winepedia\/wp-content\/uploads\/2015\/04\/^460CE01E91CA6BB77DE9C94DF6958F122A81D73268C195608E^pimgpsh_fullsize_distr1-300x300.jpg 300w, https:\/\/www.wine.com.br\/winepedia\/wp-content\/uploads\/2015\/04\/^460CE01E91CA6BB77DE9C94DF6958F122A81D73268C195608E^pimgpsh_fullsize_distr1-768x768.jpg 768w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>Ap\u00f3s o fim da colheita, nada de descanso, logo todos partiram direto para a Bodega. O primeiro passo era a sele\u00e7\u00e3o das uvas antes do desengace. Nessa etapa, os Wineanos descarregaram o caminh\u00e3o com mais de 280 caixas de uvas colhidas.<\/p>\n<p>A\u00ed, era a hora de selecionar as uvas, tirando folhas e frutos muito danificados e, tamb\u00e9m, controlar as mangueiras que levavam o mosto at\u00e9 os tanques.<\/p>\n<p>Depois de muitas horas de trabalho, ali na Bodega mesmo, a Erika proporcionou um delicioso lanche com as tradicionais empanadas argentinas e, \u00e9 claro, vinho para brindar.<\/p>\n<p>Enquanto o vinho come\u00e7ava seu processo de fermenta\u00e7\u00e3o, os Wineanos partiram para um dia de divers\u00e3o recheado de aventuras. A Erika levou todo mundo para fazer rafting, trekking e rapel em Potrerillos, um lugar com paisagens encantadoras.<\/p>\n<p><a href=\"https:\/\/www.winepedia.com.br\/wp-content\/uploads\/2015\/04\/IMG_0616.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13618\" src=\"https:\/\/www.wine.com.br\/winepedia\/wp-content\/uploads\/2015\/04\/IMG_0616.jpg\" alt=\"IMG_0616\" width=\"600\" height=\"364\" srcset=\"https:\/\/www.wine.com.br\/winepedia\/wp-content\/uploads\/2015\/04\/IMG_0616.jpg 2048w, https:\/\/www.wine.com.br\/winepedia\/wp-content\/uploads\/2015\/04\/IMG_0616-300x182.jpg 300w, https:\/\/www.wine.com.br\/winepedia\/wp-content\/uploads\/2015\/04\/IMG_0616-768x466.jpg 768w, https:\/\/www.wine.com.br\/winepedia\/wp-content\/uploads\/2015\/04\/IMG_0616-1024x621.jpg 1024w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>No roteiro, tamb\u00e9m teve um almo\u00e7o no The Vines of Mendoza, muito pr\u00f3ximo da Cordilheira dos Andes. L\u00e1, os Wineanos degustaram todos os vinhos da Bodega Goulart, incluindo um exemplar in\u00e9dito, que a Erika compartilha apenas com os amigos.<\/p>\n<p><a href=\"https:\/\/www.winepedia.com.br\/wp-content\/uploads\/2015\/04\/Foto-261.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13622\" src=\"https:\/\/www.wine.com.br\/winepedia\/wp-content\/uploads\/2015\/04\/Foto-261.jpg\" alt=\"Foto 26\" width=\"600\" height=\"450\" srcset=\"https:\/\/www.wine.com.br\/winepedia\/wp-content\/uploads\/2015\/04\/Foto-261.jpg 2048w, https:\/\/www.wine.com.br\/winepedia\/wp-content\/uploads\/2015\/04\/Foto-261-300x225.jpg 300w, https:\/\/www.wine.com.br\/winepedia\/wp-content\/uploads\/2015\/04\/Foto-261-768x576.jpg 768w, https:\/\/www.wine.com.br\/winepedia\/wp-content\/uploads\/2015\/04\/Foto-261-1024x768.jpg 1024w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>Antes de voltar para casa, foi feita uma parada na Bodega para degustar vinhos em diversos est\u00e1gios de vinifica\u00e7\u00e3o. O en\u00f3logo Jos\u00e9 Hidalgo retirou, na hora, as amostras de diversos tanques e barricas, a fim de mostrar toda a evolu\u00e7\u00e3o, at\u00e9 o vinho ficar pronto.<\/p>\n<p><a href=\"https:\/\/www.winepedia.com.br\/wp-content\/uploads\/2015\/04\/IMG_0785.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13621 \" src=\"https:\/\/www.wine.com.br\/winepedia\/wp-content\/uploads\/2015\/04\/IMG_0785.jpg\" alt=\"IMG_0785\" width=\"600\" height=\"400\" srcset=\"https:\/\/www.wine.com.br\/winepedia\/wp-content\/uploads\/2015\/04\/IMG_0785.jpg 2048w, https:\/\/www.wine.com.br\/winepedia\/wp-content\/uploads\/2015\/04\/IMG_0785-300x200.jpg 300w, https:\/\/www.wine.com.br\/winepedia\/wp-content\/uploads\/2015\/04\/IMG_0785-768x512.jpg 768w, https:\/\/www.wine.com.br\/winepedia\/wp-content\/uploads\/2015\/04\/IMG_0785-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>Confira um pouquinho do que os Wineanos sentiram:<\/p>\n<p><em>\u201cFoi incr\u00edvel a experi\u00eancia de ver de perto como paix\u00e3o e cuidado s\u00e3o inseridos nos vinhos da Bodega Goulart. Essa ess\u00eancia da vin\u00edcola sempre me encantou. Esses 5 dias retrataram exatamente como \u00e9 a amizade entre Wine.com.br e Bodega Goulart: cheia de leveza, divers\u00e3o, troca de conhecimento e adrenalina. Agrade\u00e7o profundamente, a todos os envolvidos, pela oportunidade \u00fanica.\u201d<\/em><\/p>\n<p><strong>B\u00e1rbara Wells &#8211; SRW<\/strong><\/p>\n<p><em>&#8220;Incr\u00edvel e surpreendente! Vivenciei experi\u00eancias e momentos que jamais ser\u00e3o esquecidos e que ser\u00e3o levados pra sempre em minha vida. Para mim, isso n\u00e3o tem pre\u00e7o&#8221;.<\/em><\/p>\n<p><strong>Alessandra Com\u00e9rio \u2013 Financeiro<\/strong><\/p>\n<p><em>\u201cEssa viagem foi muito marcante, desde o pouso em Mendoza, em que pude contemplar a grandiosidade e beleza da Cordilheira dos Andes, at\u00e9 os \u00faltimos instantes em terras argentinas. Pude ver de perto muita coisa que s\u00f3 conhecia na teoria, conheci profissionais muito bons, atenciosos e simples, independente de suas atribui\u00e7\u00f5es, passando pelo motorista Alberto, que ficou a nossa disposi\u00e7\u00e3o todos os dias, at\u00e9 a pr\u00f3pria Erika. Tudo perfeito: hospedagem, clima, comidas, transporte e receptividade. S\u00f3 tenho a agradecer a\u00a0<\/em><a href=\"https:\/\/wine.com.br\/\"><em>Wine.com.br<\/em><\/a><em>\u00a0e a Erika Goulart por nos proporcionar essa inesquec\u00edvel experi\u00eancia.\u201d<\/em><\/p>\n<p><strong>Enoque Nascimento &#8211; SRW<\/strong><\/p>\n<p><em>\u201cEncantada! Essa palavra resume a experi\u00eancia maravilhosa dessa viagem. Ter feito rafting, pela primeira vez, e ainda nas \u00e1guas da Cordilheira dos Andes, foi incr\u00edvel.\u201d<\/em><\/p>\n<p><strong>Lorena Tavares \u2013 Importa\u00e7\u00e3o<\/strong><\/p>\n<p>\u201c<em>O mundo do vinho n\u00e3o para de me surpreender! Nessa viagem, realizei dois sonhos: participar da colheita de um vinho que eu particularmente gosto e degustar amostras direto dos tanques e barricas. Foi tudo incr\u00edvel, intenso, divertido e reflexivo. Obrigada a todos pela oportunidade! Espero que todos um dia possam vivenciar toda essa emo\u00e7\u00e3o. <\/em><\/p>\n<p><strong>Nicole Batista \u2013 Sommeli\u00e8re<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>10 Wineanos foram sorteados para conhecer a Bodega Goulart, em Mendoza, na Argentina. Veja os detalhes dessa viagem inesquec\u00edvel. <\/p>\n","protected":false},"author":27,"featured_media":13624,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[2091,2831,2486],"class_list":["post-13543","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-experiencia-wine","tag-bodega-goulart","tag-viagem","tag-vinhos"],"_links":{"self":[{"href":"https:\/\/www.wine.com.br\/winepedia\/wp-json\/wp\/v2\/posts\/13543","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wine.com.br\/winepedia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.wine.com.br\/winepedia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.wine.com.br\/winepedia\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wine.com.br\/winepedia\/wp-json\/wp\/v2\/comments?post=13543"}],"version-history":[{"count":1,"href":"https:\/\/www.wine.com.br\/winepedia\/wp-json\/wp\/v2\/posts\/13543\/revisions"}],"predecessor-version":[{"id":26743,"href":"https:\/\/www.wine.com.br\/winepedia\/wp-json\/wp\/v2\/posts\/13543\/revisions\/26743"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.wine.com.br\/winepedia\/wp-json\/wp\/v2\/media\/13624"}],"wp:attachment":[{"href":"https:\/\/www.wine.com.br\/winepedia\/wp-json\/wp\/v2\/media?parent=13543"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.wine.com.br\/winepedia\/wp-json\/wp\/v2\/categories?post=13543"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wine.com.br\/winepedia\/wp-json\/wp\/v2\/tags?post=13543"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}