{"id":14764,"date":"2016-02-15T10:49:18","date_gmt":"2016-02-15T10:49:18","guid":{"rendered":"http:\/\/www.sommelierwine.com.br\/?p=14764"},"modified":"2020-06-09T16:13:18","modified_gmt":"2020-06-09T19:13:18","slug":"carta-de-vinhos","status":"publish","type":"post","link":"https:\/\/www.wine.com.br\/winepedia\/carta-de-vinhos\/","title":{"rendered":"Como se guiar pela carta de vinhos"},"content":{"rendered":"<p>Dentro ou fora de casa, vinho \u00e9 sempre uma boa pedida. Mas fazer a escolha certa ao analisar a <strong>carta de vinhos<\/strong> de algum estabelecimento pode ser um pouco complicado. Por isso, \u00e9 sempre bom procurar saber se voc\u00ea poder\u00e1 contar com a ajuda do Sommelier da casa.<\/p>\n<p>Contudo, se mesmo com esse recurso \u00e0 disposi\u00e7\u00e3o, voc\u00ea preferir se aventurar, seguem algumas dicas valiosas:<\/p>\n<h4>Saiba por onde come\u00e7ar<\/h4>\n<p>Qual o objetivo da escolha do vinho? Ele ser\u00e1 a estrela da mesa? J\u00e1 pensou em algum prato espec\u00edfico? Se sim, ajuste-o sempre ao vinho ou vice-versa. O bom \u00e9 saber por onde come\u00e7ar. Se pedir uma salada leve ou uma massa com molho encorpado, siga o mesmo caminho com o peso do vinho.<\/p>\n<h4>Seja paciente e procure agradar<\/h4>\n<p>Se estiver sendo o anfitri\u00e3o do momento, pergunte o que as pessoas gostariam de conhecer ou beber. Procure saber se elas t\u00eam prefer\u00eancia por algum pa\u00eds ou estilo. Muitas vezes, a experi\u00eancia com o vinho \u00e9 que merecer\u00e1 o destaque da noite e n\u00e3o necessariamente ele precisar\u00e1 ser harmonizado.<\/p>\n<h4>Fator pre\u00e7o<\/h4>\n<p>O vinho mais caro pode ser melhor do que um mais barato, mas o contr\u00e1rio tamb\u00e9m ocorre. Nem sempre o que agradar\u00e1 seu paladar ser\u00e1 o de maior custo. Sendo assim, procure a faixa de pre\u00e7o que melhor se adapte \u00e0 ocasi\u00e3o. Outro fator que determina o valor \u00e9 o tamanho da garrafa. Se poucas pessoas optarem por vinho durante a refei\u00e7\u00e3o, procure saber se o estabelecimento tem op\u00e7\u00f5es de meia garrafa (375 ml), o que evita desperd\u00edcio. Em alguns casos, pode ser mais vi\u00e1vel pedir a garrafa inteira ao inv\u00e9s de v\u00e1rias ta\u00e7as.<\/p>\n<h4>Alguns dados estar\u00e3o, quase sempre, dispon\u00edveis<\/h4>\n<p>Em uma carta de vinhos, geralmente, aparecem informa\u00e7\u00f5es como a safra, o nome do vinho, o produtor, a uva, a regi\u00e3o, o pa\u00eds e o pre\u00e7o. Se oriente pelas experi\u00eancias que j\u00e1 possui ou pelas curiosidades que tem.<\/p>\n<h4>Busque compreender a proposta do estabelecimento<\/h4>\n<p>Se o local for tem\u00e1tico, muitas vezes a carta de vinhos segue a mesma tend\u00eancia, embora tenha outras op\u00e7\u00f5es de r\u00f3tulos. Se for a um restaurante italiano, muito prov\u00e1vel que a maioria dos exemplares\u00a0seja do mesmo pa\u00eds, por exemplo. Que tal dar uma pesquisada antes em como s\u00e3o os vinhos para ser mais certeiro em sua escolha? A outra op\u00e7\u00e3o \u00e9 se render \u00e0s escolhas do local e arriscar conhecer exemplares de diferentes pa\u00edses ou regi\u00f5es.<\/p>\n<h4>Em caso de muitas d\u00favidas&#8230;<\/h4>\n<p>Se mesmo seguindo as dicas \u00e0 risca ainda ficou aquela d\u00favida na decis\u00e3o final, n\u00e3o hesite. Chame o Sommelier para esclarecer alguns pontos. Voc\u00ea pode tamb\u00e9m, durante a escolha, ir conversando com o profissional. Quanto mais ele conhecer seu gosto, mais f\u00e1cil e certeira ser\u00e1 a escolha do vinho perfeito.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Veja dicas preciosas do que fazer quando estiver com a carta de vinhos de um estabelecimento em m\u00e3os.<\/p>\n","protected":false},"author":27,"featured_media":14765,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[2159,3041,2486],"class_list":["post-14764","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dicas","tag-carta-de-vinhos","tag-escolha","tag-vinhos"],"_links":{"self":[{"href":"https:\/\/www.wine.com.br\/winepedia\/wp-json\/wp\/v2\/posts\/14764","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wine.com.br\/winepedia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.wine.com.br\/winepedia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.wine.com.br\/winepedia\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wine.com.br\/winepedia\/wp-json\/wp\/v2\/comments?post=14764"}],"version-history":[{"count":0,"href":"https:\/\/www.wine.com.br\/winepedia\/wp-json\/wp\/v2\/posts\/14764\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.wine.com.br\/winepedia\/wp-json\/wp\/v2\/media\/14765"}],"wp:attachment":[{"href":"https:\/\/www.wine.com.br\/winepedia\/wp-json\/wp\/v2\/media?parent=14764"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.wine.com.br\/winepedia\/wp-json\/wp\/v2\/categories?post=14764"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wine.com.br\/winepedia\/wp-json\/wp\/v2\/tags?post=14764"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}