{"id":21157,"date":"2019-10-01T08:00:54","date_gmt":"2019-10-01T11:00:54","guid":{"rendered":"https:\/\/www.wine.com.br\/winepedia\/?p=21157"},"modified":"2020-06-09T16:23:45","modified_gmt":"2020-06-09T19:23:45","slug":"nota-por-nota","status":"publish","type":"post","link":"https:\/\/www.wine.com.br\/winepedia\/nota-por-nota\/","title":{"rendered":"Nota por nota no Dia Mundial da M\u00fasica"},"content":{"rendered":"<p>Dia 01 de outubro \u00e9 data para homenagear uma das formas de arte mais queridas pela popula\u00e7\u00e3o do Planeta: a m\u00fasica. <\/p>\n<p>O Dia Mundial da M\u00fasica surgiu em 1975, a partir de uma iniciativa da UNESCO, com o objetivo de promover a paz entre os povos com o aux\u00edlio dos ritmos e sons. <\/p>\n<p>E j\u00e1 que estamos falando sobre uma paix\u00e3o universal, por que n\u00e3o unirmos mais uma em um casamento perfeito? Eu ouvi algu\u00e9m falando \u201cvinho\u201d?!<\/p>\n<p>Isso mesmo. Reunimos alguns dos estilos musicais mais queridos e relacionamos a vinhos imperd\u00edveis. Som na caixa e sa\u00fade!<\/p>\n<p><strong>MPB <\/strong><br \/>\nDo ax\u00e9 ao sertanejo at\u00e9 a bossa nova: Do banquinho ao viol\u00e3o ao relax de um entardecer na praia. \u00d3timo para compartilhar com os  amigos ou namorados.<\/p>\n<p>Que tal um <a href=\"https:\/\/www.wine.com.br\/mega-cupom\/espumante-gran-legado-champenoise-vale-dos-vinhedos-rose-brut\/prod19690.html\" rel=\"noopener noreferrer\" target=\"_blank\">espumante bem brasileiro<\/a> ou um belo <a href=\"https:\/\/www.wine.com.br\/mega-cupom\/carpineto-dogajolo-rosato-2018\/prod22064.html\" rel=\"noopener noreferrer\" target=\"_blank\">vinho ros\u00e9<\/a>? <\/p>\n<p><strong>ROCK&#8217;N&#8217;ROLL<\/strong><br \/>\nO rock pode ser denso ou viajante e, muitas vezes, as duas coisas! \u00c0s vezes barulhento, outras, harmonioso, uma coisa artistas como Chuck Berry, Led Zeppelin, Rolling Stones, Pearl Jam, Foo Fighters, Strokes e muito mais t\u00eam em comum: com sua m\u00fasica \u00e9 imposs\u00edvel ficar parado.<\/p>\n<p>Vamos harmoniz\u00e1-lo com uma garrafa de <a href=\"https:\/\/www.wine.com.br\/vinhos\/ghost-pines-winemakers-blend-red-2016\/prod22144.html\" rel=\"noopener noreferrer\" target=\"_blank\">um potente californiano<\/a>? Acerte a\u00ed!<\/p>\n<p><strong>ELETR\u00d4NICA<\/strong><br \/>\nDe Kraftwerk, Giorgio Moroder, Daft Punk, Prodigy a tantos DJs espalhados pelo mundo, o que queremos do eletr\u00f4nico \u00e9 algo agitado, forte e agregador. Afinal, fica muito melhor se compartilhado em uma festa. <\/p>\n<p>Vai muito bem ent\u00e3o com um <a href=\"https:\/\/www.wine.com.br\/mega-cupom\/el-bautismo-blend-de-tintas-2018\/prod22218.html\" rel=\"noopener noreferrer\" target=\"_blank\">r\u00f3tulo descompromissado<\/a> e excelente para dividir com a galera. <\/p>\n<p><strong>ERUDITA<\/strong><br \/>\nPara quem aprecia os cl\u00e1ssicos, compostos com cuidado, min\u00facia. Play em um dos g\u00eanios da \u00e1rea \u00e9 certeza de satisfa\u00e7\u00e3o. Ent\u00e3o vem no sabor de um <a href=\"https:\/\/www.wine.com.br\/vinhos\/beni-di-batasiolo-d-o-c-g-barolo-2014\/prod19840.html\" rel=\"noopener noreferrer\" target=\"_blank\">Barolo cl\u00e1ssico<\/a> que a sinfonia de sabores \u00e9 irresist\u00edvel. <\/p>\n<p><strong>REGGAE<\/strong><br \/>\nNotas suaves e o clima de tranquilidade \u00e9 tudo o que h\u00e1 de melhor no reggae. Mas n\u00e3o se engane: sua mensagem \u00e9 de amor, mas tamb\u00e9m \u00e9 pol\u00edtica, desde os cl\u00e1ssicos jamaicanos como Skatalites, Bob Marley, Peter Tosh, The Wailers e Max Romeo. <\/p>\n<p>Algo refrescante e ao mesmo tempo poderoso. Como esse <a href=\"https:\/\/www.wine.com.br\/mega-cupom\/que-guapo-branco-2018\/prod22093.html\" rel=\"noopener noreferrer\" target=\"_blank\">exemplar da Argentina aqui<\/a>. I wanna love you!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aproveite esta data para combinar estilos a vinhos maravilhosos em harmoniza\u00e7\u00f5es cheias de ritmo<\/p>\n","protected":false},"author":27,"featured_media":21169,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[4117,112,3342,3370,3371],"class_list":["post-21157","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-harmonizacao-de-a-a-w","tag-eletronica","tag-harmonizacao","tag-mpb","tag-musica","tag-rock"],"_links":{"self":[{"href":"https:\/\/www.wine.com.br\/winepedia\/wp-json\/wp\/v2\/posts\/21157","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wine.com.br\/winepedia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.wine.com.br\/winepedia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.wine.com.br\/winepedia\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wine.com.br\/winepedia\/wp-json\/wp\/v2\/comments?post=21157"}],"version-history":[{"count":0,"href":"https:\/\/www.wine.com.br\/winepedia\/wp-json\/wp\/v2\/posts\/21157\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.wine.com.br\/winepedia\/wp-json\/wp\/v2\/media\/21169"}],"wp:attachment":[{"href":"https:\/\/www.wine.com.br\/winepedia\/wp-json\/wp\/v2\/media?parent=21157"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.wine.com.br\/winepedia\/wp-json\/wp\/v2\/categories?post=21157"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wine.com.br\/winepedia\/wp-json\/wp\/v2\/tags?post=21157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}